{"id":14032,"date":"2022-08-27T00:08:11","date_gmt":"2022-08-27T00:08:11","guid":{"rendered":"https:\/\/peace-ipsc.org\/fa\/?p=14032"},"modified":"2022-08-27T00:08:11","modified_gmt":"2022-08-27T00:08:11","slug":"%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c","status":"publish","type":"post","link":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/","title":{"rendered":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc"},"content":{"rendered":"<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><strong>\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc<\/strong><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><strong>\u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9<\/strong><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><strong>\u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d- IPSC<\/strong><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0634\u0627\u0645\u0644 \u0647\u0641\u062a \u0627\u0645\u0627\u0631\u062a &#8211; \u0627\u0628\u0648\u0638\u0628\u06cc\u060c \u0639\u062c\u0645\u0627\u0646\u060c \u062f\u0628\u06cc\u060c \u0641\u062c\u06cc\u0631\u0647\u060c \u0631\u0627\u0633 \u0627\u0644\u062e\u06cc\u0645\u0647\u060c \u0634\u0627\u0631\u062c\u0647 \u0648 \u0627\u0645 \u0627\u0644\u0642\u0648\u06cc\u0646 &#8211; \u0648\u0627\u0642\u0639 \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0633\u0627\u062d\u0644 \u062c\u0646\u0648\u0628 \u0634\u0631\u0642\u06cc \u0634\u0628\u0647 \u062c\u0632\u06cc\u0631\u0647 \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0632 \u0632\u0645\u0627\u0646 \u06a9\u0634\u0641 \u0646\u0641\u062a \u062f\u0631 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\u060c \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06a9\u0634\u0648\u0631\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0628\u0627 \u0633\u0637\u062d \u0632\u0646\u062f\u06af\u06cc \u0628\u0627\u0644\u0627 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0632 \u0627\u06cc\u0646 \u0644\u062d\u0627\u0638 \u0647\u06cc\u062f\u0631\u0648\u06a9\u0631\u0628\u0646 \u0647\u0627 \u0647\u0645\u0686\u0646\u0627\u0646 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0645\u0627\u0631\u0627\u062a \u0627\u06cc\u0641\u0627 \u0645\u06cc \u06a9\u0646\u0646\u062f\u060c \u0628\u0647 \u0637\u0648\u0631\u06cc \u06a9\u0647 30 \u062f\u0631\u0635\u062f \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f \u0646\u0627\u062e\u0627\u0644\u0635 \u062f\u0627\u062e\u0644\u06cc \u0627\u0645\u0627\u0631\u0627\u062a \u0628\u0647 \u0637\u0648\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0631 \u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0648 13 \u062f\u0631\u0635\u062f \u0627\u0632 \u0635\u0627\u062f\u0631\u0627\u062a \u0622\u0646 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u062f\u0631 \u0633\u0627\u0644 1967 \u0628\u0647 \u06a9\u0646\u0633\u0631\u0633\u06cc\u0648\u0645 \u0627\u0648\u067e\u06a9 \u067e\u06cc\u0648\u0633\u062a.<\/span><\/p>\n<p dir=\"rtl\"><span style=\"font-size: 12pt\"><!--more--><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0634\u0634\u0645\u06cc\u0646 \u0630\u062e\u0627\u06cc\u0631 \u0627\u062b\u0628\u0627\u062a \u0634\u062f\u0647 \u0646\u0641\u062a \u062c\u0647\u0627\u0646 \u0648 \u067e\u0646\u062c\u0645\u06cc\u0646 \u0630\u062e\u0627\u06cc\u0631 \u0628\u0632\u0631\u06af \u06af\u0627\u0632 \u0637\u0628\u06cc\u0639\u06cc \u0631\u0627 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06cc\u06a9 \u062d\u06cc\u0627\u062a\u06cc \u0648 \u062a\u0627\u0645\u06cc\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0645\u0633\u0626\u0648\u0644 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0627\u0646\u0631\u0698\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u0628\u0648\u0638\u0628\u06cc 94 \u062f\u0631\u0635\u062f \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0646\u0641\u062a\u06cc \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u06cc\u0627 \u062d\u062f\u0648\u062f 2\/92 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0628\u0634\u06a9\u0647 \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f. \u062f\u0628\u06cc \u062d\u062f\u0648\u062f 4 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0628\u0634\u06a9\u0647 \u0648 \u067e\u0633 \u0627\u0632 \u0622\u0646 \u0634\u0627\u0631\u062c\u0647 \u0648 \u0631\u0627\u0633 \u0627\u0644\u062e\u06cc\u0645\u0647 \u0628\u0647 \u062a\u0631\u062a\u06cc\u0628 \u0628\u0627 5\/1 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 100 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u0646\u0641\u062a \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u0646\u062f. \u0627\u0628\u0648\u0638\u0628\u06cc \u0633\u0627\u0628\u0642\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u0628\u062e\u0634 \u062e\u0635\u0648\u0635\u06cc \u062f\u0631 \u0628\u062e\u0634 \u0628\u0627\u0644\u0627\u062f\u0633\u062a \u0627\u06a9\u062a\u0634\u0627\u0641 \u0648 \u062a\u0648\u0644\u06cc\u062f \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u062f\u0627\u0631\u062f. \u0627\u0628\u0648\u0638\u0628\u06cc \u062a\u0646\u0647\u0627 \u0639\u0636\u0648 \u0627\u0648\u067e\u06a9 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0637\u0648\u0644 \u0645\u0648\u062c \u0645\u0644\u06cc \u0634\u062f\u0646 \u0635\u0646\u0639\u062a \u062c\u0647\u0627\u0646\u06cc \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u062f\u0631 \u0627\u0648\u0627\u0633\u0637 \u062f\u0647\u0647 1970\u060c \u0633\u0631\u0645\u0627\u06cc\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u0627\u0646 \u062e\u0627\u0631\u062c\u06cc \u0631\u0627 \u0645\u0644\u06cc \u0646\u06a9\u0631\u062f \u0648 \u0647\u0645\u0686\u0646\u0627\u0646 \u0627\u0632 \u0633\u0637\u062d \u0628\u0627\u0644\u0627\u06cc\u06cc \u0627\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0628\u062e\u0634 \u062e\u0635\u0648\u0635\u06cc \u0628\u0647\u0631\u0647 \u0645\u0646\u062f \u0627\u0633\u062a.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0637\u0628\u0642 \u0627\u0639\u0644\u0627\u0645 \u0634\u0631\u06a9\u062a \u0627\u062f\u0646\u0648\u06a9\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0631\u0648\u0632\u0627\u0646\u0647 \u062d\u062f\u0648\u062f \u06f3 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u0646\u0641\u062a \u0648 \u06f1\u06f0 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f5\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0641\u0648\u062a \u0645\u06a9\u0639\u0628 \u06af\u0627\u0632 \u062a\u0648\u0644\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0646\u062a\u0638\u0627\u0631 \u0645\u06cc \u0631\u0648\u062f \u062a\u0627 \u0633\u0627\u0644 2030 \u0628\u0647 \u062d\u062f\u0627\u06a9\u062b\u0631 \u0638\u0631\u0641\u06cc\u062a \u062a\u0648\u0644\u06cc\u062f \u067e\u0627\u06cc\u062f\u0627\u0631 5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u0628\u0631\u0633\u062f. \u0645\u06cc\u062f\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0641\u062a\u06cc \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0628\u0627 \u0630\u062e\u06cc\u0631\u0647 \u06f9\u06f7 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f8\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u0646\u0641\u062a\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0631\u0627 \u062f\u0631 \u0631\u062a\u0628\u0647 \u0647\u0634\u062a\u0645 \u06a9\u0634\u0648\u0631 \u062f\u0627\u0631\u0646\u062f\u0647 \u0630\u062e\u0627\u06cc\u0631 \u0639\u0638\u06cc\u0645 \u0646\u0641\u062a\u06cc \u062f\u0631 \u0645\u06cc\u0627\u0646 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u062f\u0631 \u062d\u0627\u0644\u06cc\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 2020\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0627\u0632 \u06a9\u0634\u0641 \u0628\u06cc\u0634 \u0627\u0632 80 \u062a\u0631\u06cc\u0644\u06cc\u0648\u0646 \u0641\u0648\u062a \u0645\u06a9\u0639\u0628 \u0645\u0646\u0627\u0628\u0639 \u06af\u0627\u0632\u06cc \u062f\u0631 \u062c\u0628\u0644 \u0639\u0644\u06cc \u062e\u0628\u0631 \u062f\u0627\u062f. \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0630\u062e\u0627\u06cc\u0631 \u062b\u0627\u0628\u062a\u06cc \u0645\u0639\u0627\u062f\u0644 299.0 \u0628\u0631\u0627\u0628\u0631 \u0645\u0635\u0631\u0641 \u0633\u0627\u0644\u0627\u0646\u0647 \u062e\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u062f\u0648\u0646 \u0635\u0627\u062f\u0631\u0627\u062a \u062e\u0627\u0644\u0635\u060c \u062d\u062f\u0648\u062f 299 \u0633\u0627\u0644 \u0646\u0641\u062a \u0628\u0627\u0642\u06cc \u0645\u06cc \u0645\u0627\u0646\u062f(1). \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u0627\u0645\u0627\u0646\u0647 \u0627\u0646\u0631\u0698\u06cc \u0647\u0627\u06cc \u062a\u062c\u062f\u06cc\u062f \u067e\u0630\u06cc\u0631 \u0648 \u0628\u0647\u0631\u0647 \u0648\u0631\u06cc \u0627\u0646\u0631\u0698\u06cc \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u0645\u06cc \u06a9\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-weight: 400\">\u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u067e\u06cc\u0634\u0631\u0648 \u062c\u0647\u0627\u0646\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0641\u0639\u0627\u0644 \u062f\u0631 \u062a\u0645\u0627\u0645 \u0628\u062e\u0634 \u0647\u0627\u06cc \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0627\u0633\u062a. \u0636\u0645\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0648 \u062a\u0627 \u0627\u0632 \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632 <\/span><span style=\"font-weight: 400\">ADNOC Onshore<\/span><span style=\"font-weight: 400\"> \u0648 <\/span><span style=\"font-weight: 400\">ADNOC Offshore<\/span><span style=\"font-weight: 400\"> \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u062a\u0648\u0644\u06cc\u062f \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0631\u0627 \u0628\u0647 \u062e\u0648\u062f \u0627\u062e\u062a\u0635\u0627\u0635 \u0645\u06cc \u062f\u0647\u0646\u062f(2).\u00a0 \u0644\u0627\u0632\u0645 \u0628\u0647 \u0630\u06a9\u0631 \u0627\u0633\u062a \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0646\u0641\u062a \u0627\u0632 \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627\u060c \u0698\u0627\u067e\u0646\u060c \u0641\u0631\u0627\u0646\u0633\u0647\u060c \u0627\u0646\u06af\u0644\u06cc\u0633 \u0648 \u0633\u0627\u06cc\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627 \u0633\u0647\u0627\u0645 \u0645\u0634\u062a\u0631\u06a9 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0628\u06cc\u0646 40 \u062a\u0627 100 \u062f\u0631\u0635\u062f \u0631\u0627 \u062f\u0631 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u06af\u0633\u062a\u0631\u062f\u0647 \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u0646\u062f. \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0628\u06cc\u0634 \u0627\u0632 40 \u062f\u0631\u0635\u062f \u0627\u0632 \u0646\u0641\u062a \u062e\u0627\u0645 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0698\u0627\u067e\u0646 \u0635\u0627\u062f\u0631 \u0645\u06cc \u06a9\u0646\u062f \u0648 \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u0645\u0634\u062a\u0631\u06cc \u0627\u0645\u0627\u0631\u0627\u062a \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0639\u0645\u062f\u062a\u0627 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0648\u0627\u0642\u0639\u06cc\u062a \u0647\u0627\u06cc \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u062a\u0623\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0631 \u0647\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u062d\u062f\u0627\u0642\u0644 \u0645\u0642\u0627\u062f\u06cc\u0631 \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u0635\u0627\u062f\u0631 \u0645\u06cc \u06a9\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u0648\u062c\u0648\u062f\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u062a\u0623\u0645\u06cc\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0645\u0647\u0645 \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0627\u0633\u062a \u0648 \u0627\u0632 \u0646\u0638\u0631 \u0638\u0631\u0641\u06cc\u062a \u062a\u0648\u0644\u06cc\u062f \u0646\u0641\u062a \u0627\u0636\u0627\u0641\u06cc \u0628\u0639\u062f \u0627\u0632 \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0633\u0639\u0648\u062f\u06cc \u062f\u0631 \u0631\u062a\u0628\u0647 \u062f\u0648\u0645 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f.<\/span><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-weight: 400\">\u067e\u0631\u0648\u0698\u0647 \u062f\u0644\u0641\u06cc\u0646 \u06a9\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062e\u0637 \u0644\u0648\u0644\u0647 \u0642\u0637\u0631 \u0628\u0647 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u06af\u0627\u0632 \u0637\u0628\u06cc\u0639\u06cc \u0648\u0627\u0631\u062f \u0645\u06cc \u06a9\u0646\u062f\u060c \u0627\u0648\u0644\u06cc\u0646 \u062a\u0648\u0627\u0641\u0642 \u0645\u0647\u0645 \u0628\u06cc\u0646 \u0645\u0631\u0632\u06cc \u0627\u0646\u0631\u0698\u06cc \u0628\u06cc\u0646 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062d\u0627\u0634\u06cc\u0647 \u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u067e\u0631\u0648\u0698\u0647 \u06af\u0627\u0632 \u0627\u0628\u0648\u0638\u0628\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0648 \u0635\u0627\u062f\u0631\u0627\u062a \u0646\u0641\u062a \u062e\u0627\u0645 \u0622\u0632\u0627\u062f \u0645\u06cc \u06a9\u0646\u062f. \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc \u0627\u06a9\u0633\u06cc\u062f\u0646\u062a\u0627\u0644 \u067e\u062a\u0631\u0648\u0644\u06cc\u0648\u0645<\/span> <span style=\"font-weight: 400\">\u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u062a\u0648\u062a\u0627\u0644 \u0641\u0631\u0627\u0646\u0633\u0647 \u0647\u0631\u06a9\u062f\u0627\u0645 5\/24 \u062f\u0631\u0635\u062f \u0627\u0632 \u0633\u0647\u0627\u0645 \u0627\u06cc\u0646 \u067e\u0631\u0648\u0698\u0647 \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0648\u0644\u062a \u0627\u0628\u0648\u0638\u0628\u06cc 51 \u062f\u0631\u0635\u062f \u0628\u0627\u0642\u06cc\u0645\u0627\u0646\u062f\u0647 \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f. \u0627\u0648\u0644\u06cc\u0646 \u062a\u062d\u0648\u06cc\u0644 \u062a\u062c\u0627\u0631\u06cc \u06af\u0627\u0632 \u0637\u0628\u06cc\u0639\u06cc \u0642\u0637\u0631 \u0628\u0647 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0627\u0632 \u062a\u0627\u0628\u0633\u062a\u0627\u0646 2007 \u0622\u063a\u0627\u0632 \u0634\u062f \u0648 \u062f\u0631 \u0637\u0648\u0644 30 \u0633\u0627\u0644 \u0627\u0632 \u062a\u0648\u0627\u0641\u0642 \u0646\u0627\u0645\u0647 \u062a\u0648\u0633\u0639\u0647 \u0648 \u062a\u0642\u0633\u06cc\u0645 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u062f\u0648\u0644\u062a \u0642\u0637\u0631 \u0627\u0645\u0636\u0627 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a.<\/span><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u062e\u0637\u0648\u0637 \u0644\u0648\u0644\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 5\/6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u0646\u0641\u062a \u062f\u0631 \u0631\u0648\u0632 \u06cc\u0627 \u062d\u062f\u0648\u062f 40 \u062f\u0631\u0635\u062f \u0627\u0632 \u0645\u0642\u062f\u0627\u0631 \u0641\u0639\u0644\u06cc \u062d\u0645\u0644 \u0634\u062f\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062a\u0646\u06af\u0647 \u062c\u0627\u0628\u062c\u0627 \u0634\u0648\u0646\u062f. \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u062e\u0637\u0648\u0637 \u0644\u0648\u0644\u0647\u060c \u0627\u062a\u0635\u0627\u0644 \u0645\u06cc\u062f\u0627\u0646 \u0646\u0641\u062a\u06cc \u062d\u0628\u0634\u0627\u0646 \u062f\u0631 \u0627\u0628\u0648\u0638\u0628\u06cc \u0648 \u0628\u0646\u062f\u0631 \u0641\u062c\u06cc\u0631\u0647\u060c \u0628\u0647 \u0627\u0645\u0627\u0631\u0627\u062a \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u062d\u062f\u0648\u062f 60 \u062f\u0631\u0635\u062f \u0627\u0632 \u0635\u0627\u062f\u0631\u0627\u062a \u0646\u0641\u062a \u062e\u0627\u0645 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0628\u0646\u062f\u0631 \u0641\u062c\u06cc\u0631\u0647 \u062f\u0631 \u062e\u0644\u06cc\u062c \u0639\u0645\u0627\u0646 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0646\u062f. \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0647\u0645\u0686\u0646\u0627\u0646 \u062a\u0648\u0644\u06cc\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0627\u0646\u0631\u0698\u06cc \u0628\u0647 \u0637\u0648\u0631 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc \u062f\u0647\u062f. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0628\u0631\u062e\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0627\u0648\u067e\u06a9 \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u063a\u06cc\u0631 \u0627\u0648\u067e\u06a9 \u0637\u06cc \u067e\u0646\u062c \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0634\u0627\u0647\u062f \u06a9\u0627\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u0628\u0648\u062f\u0647 \u0627\u0646\u062f\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u062a\u0648\u0644\u06cc\u062f \u06a9\u0644 \u0646\u0641\u062a \u062e\u0627\u0645 \u062e\u0648\u062f \u0631\u0627 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 31 \u062f\u0631\u0635\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a(3). \u0628\u062f\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628 \u0645\u0642\u0635\u062f \u0627\u0635\u0644\u06cc \u0635\u0627\u062f\u0631\u0627\u062a \u0646\u0641\u062a \u062e\u0627\u0645 \u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632: \u0698\u0627\u067e\u0646 (12.1 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631)\u060c \u0686\u06cc\u0646 (8.6 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631)\u060c \u0647\u0646\u062f (6.34 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631)\u060c \u062a\u0627\u06cc\u0644\u0646\u062f (3.84 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631) \u0648 \u06a9\u0631\u0647 \u062c\u0646\u0648\u0628\u06cc (3.18 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0647\u0633\u062a\u0646\u062f(3). \u0635\u0627\u062f\u0631\u0627\u062a \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0628\u062f\u0648\u0646 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0647\u0645\u0647\u200c\u06af\u06cc\u0631\u06cc\u060c \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0628\u0648\u062f. \u0628\u062f\u0648\u0646 \u0634\u06a9 \u062a\u0645\u0631\u06a9\u0632 \u0642\u0648\u06cc \u0628\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0622\u0633\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0627\u0645\u0631 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a(4).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0636\u0645\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc\u00a0 \u0647\u0632\u06cc\u0646\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06f4\u06f4\u06f8 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0631\u0647\u0645\u06cc (\u06f1\u06f2\u06f1 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f9\u06f7\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631\u06cc) \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u0628\u0631\u0627\u06cc \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u06f2\u06f0\u06f2\u06f1 \u062a\u0627 \u06f2\u06f0\u06f2\u06f5 \u0631\u0627 \u062a\u0635\u0648\u06cc\u0628 \u06a9\u0631\u062f. \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0639\u0637\u0627\u06cc \u062f\u0648\u0631 \u062f\u0648\u0645 \u0628\u0644\u0648\u06a9\u200c\u0647\u0627\u06cc \u0627\u06a9\u062a\u0634\u0627\u0641\u06cc \u0631\u0627 \u062a\u0635\u0648\u06cc\u0628 \u06a9\u0631\u062f \u0648 \u0627\u0632 \u06a9\u0634\u0641 \u06f2 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0628\u0634\u06a9\u0647 \u0630\u062e\u0627\u06cc\u0631 \u0646\u0641\u062a\u06cc \u0645\u062a\u0639\u0627\u0631\u0641 \u0648 \u06f2\u06f2 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0628\u0634\u06a9\u0647 \u0630\u062e\u0627\u06cc\u0631 \u0646\u0641\u062a\u06cc \u0646\u0627\u0645\u062a\u0639\u0627\u0631\u0641 \u062e\u0628\u0631 \u062f\u0627\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u0637\u0631\u062d\u060c \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0646\u0641\u062a \u0627\u0628\u0648\u0638\u0628\u06cc \u0642\u0635\u062f \u062f\u0627\u0631\u062f \u06f1\u06f6\u06f0 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0631\u0647\u0645 (6\/43 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631) \u0631\u0627 \u0628\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u062d\u0644\u06cc \u0627\u0645\u0627\u0631\u0627\u062a \u062f\u0631 \u0628\u0627\u0632\u0647 \u0632\u0645\u0627\u0646\u06cc \u06f2\u06f0\u06f2\u06f1-\u06f2\u06f0\u06f2\u06f5 \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f. \u0636\u0645\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0646\u0641\u062a \u0627\u0645\u0627\u0631\u0627\u062a \u0646\u06cc\u0632 \u0627\u0632 \u06a9\u0634\u0641 \u0630\u062e\u0627\u06cc\u0631 \u062a\u0627\u0632\u0647 \u06a9\u0634\u0641 \u0634\u062f\u0647 \u062d\u0627\u0648\u06cc \u06f7\u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0628\u0634\u06a9\u0647 \u0646\u0641\u062a \u0648 \u06f5\u06f8 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0641\u0648\u062a \u0645\u06a9\u0639\u0628 \u06af\u0627\u0632 \u0637\u0628\u06cc\u0639\u06cc \u062e\u0628\u0631 \u062f\u0627\u062f\u0647 \u0628\u0648\u062f. \u067e\u06cc\u0634 \u0627\u0632 \u0627\u0639\u0644\u0627\u0645 \u0627\u06cc\u0646 \u0627\u06a9\u062a\u0634\u0627\u0641\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0628\u0627 \u06f9\u06f7 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f8\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0628\u0634\u06a9\u0647 \u062f\u0631 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0647\u0634\u062a\u0645 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u0627\u0631\u0646\u062f\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0630\u062e\u0627\u06cc\u0631 \u0646\u0641\u062a\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u0634\u062a \u0648 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0648\u0646\u0632\u0648\u0626\u0644\u0627 (\u0628\u0627 \u06f2\u06f9\u06f8 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f4\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646)\u060c \u0639\u0631\u0628\u0633\u062a\u0627\u0646 (\u0628\u0627\u06f2\u06f6\u06f3 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f3\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646)\u060c \u06a9\u0627\u0646\u0627\u062f\u0627 (\u0628\u0627 \u06f1\u06f7\u06f1 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f)\u060c \u0627\u06cc\u0631\u0627\u0646 (\u0628\u0627 \u06f1\u06f5\u06f7 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f8\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646) \u060c \u0639\u0631\u0627\u0642 (\u0628\u0627 \u06f1\u06f4\u06f4 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f2\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646)\u060c \u06a9\u0648\u06cc\u062a (\u0628\u0627 \u06f1\u06f0\u06f4 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f) \u0648 \u0631\u0648\u0633\u06cc\u0647 (\u0628\u0627 \u06f1\u06f0\u06f3 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0648 \u06f2\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646) \u0628\u0634\u06a9\u0647 \u0628\u0627\u0644\u0627\u062a\u0631 \u0627\u0632 \u0622\u0646 \u06a9\u0634\u0648\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u0634\u062a\u0646\u062f(5).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\"><strong>\u06a9\u0644\u06cc\u062f \u0648\u0627\u0698\u06af\u0627\u0646:<\/strong> <strong>\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc, \u0627\u0646\u0631\u0698\u06cc, \u0646\u0641\u062a, \u06af\u0627\u0632, \u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633,\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc<\/strong><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"ltr\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 8pt\">1-https:\/\/www.worldometers.info\/oil\/united-arab-emirates-oil\/<\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 8pt\">2-https:\/\/www.trade.gov\/country-commercial-guides\/united-arab-emirates-oil-and-gas<\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 8pt\">3- https:\/\/www.uae-embassy.org\/about-uae\/energy-uae<\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 8pt\">4-https:\/\/www.hellenicshippingnews.com\/uae-crude-oil-exports-have-suffered-since-the-start-of-2021\/<\/span><\/p>\n<p dir=\"ltr\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 8pt\">5-https:\/\/oec.world\/en\/profile\/bilateral-product\/crude-petroleum\/reporter\/are<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d- IPSC \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0634\u0627\u0645\u0644 \u0647\u0641\u062a \u0627\u0645\u0627\u0631\u062a &#8211; \u0627\u0628\u0648\u0638\u0628\u06cc\u060c \u0639\u062c\u0645\u0627\u0646\u060c \u062f\u0628\u06cc\u060c \u0641\u062c\u06cc\u0631\u0647\u060c \u0631\u0627\u0633 \u0627\u0644\u062e\u06cc\u0645\u0647\u060c \u0634\u0627\u0631\u062c\u0647 \u0648 \u0627\u0645 \u0627\u0644\u0642\u0648\u06cc\u0646 &#8211; \u0648\u0627\u0642\u0639 \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0633\u0627\u062d\u0644 \u062c\u0646\u0648\u0628 \u0634\u0631\u0642\u06cc \u0634\u0628\u0647 \u062c\u0632\u06cc\u0631\u0647 \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0632 \u0632\u0645\u0627\u0646 \u06a9\u0634\u0641 \u0646\u0641\u062a \u062f\u0631 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\u060c \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06a9\u0634\u0648\u0631\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0628\u0627 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,933,9,2,11,3],"tags":[46,157,50,1391,3072,442],"class_list":["post-14032","post","type-post","status-publish","format-standard","hentry","category-21","category-933","category-9","category-2","category-11","category-articles","tag-46","tag-157","tag-50","tag-1391","tag-3072","tag-442"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/peace-ipsc.org\/fa\/\u0635\u0646\u0639\u062a-\u0646\u0641\u062a-\u0648-\u06af\u0627\u0632-\u0627\u0645\u0627\u0631\u0627\u062a-\u0645\u062a\u062d\u062f\u0647-\u0639\u0631\u0628\u06cc\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d- IPSC \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0634\u0627\u0645\u0644 \u0647\u0641\u062a \u0627\u0645\u0627\u0631\u062a &#8211; \u0627\u0628\u0648\u0638\u0628\u06cc\u060c \u0639\u062c\u0645\u0627\u0646\u060c \u062f\u0628\u06cc\u060c \u0641\u062c\u06cc\u0631\u0647\u060c \u0631\u0627\u0633 \u0627\u0644\u062e\u06cc\u0645\u0647\u060c \u0634\u0627\u0631\u062c\u0647 \u0648 \u0627\u0645 \u0627\u0644\u0642\u0648\u06cc\u0646 &#8211; \u0648\u0627\u0642\u0639 \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0633\u0627\u062d\u0644 \u062c\u0646\u0648\u0628 \u0634\u0631\u0642\u06cc \u0634\u0628\u0647 \u062c\u0632\u06cc\u0631\u0647 \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0632 \u0632\u0645\u0627\u0646 \u06a9\u0634\u0641 \u0646\u0641\u062a \u062f\u0631 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\u060c \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06a9\u0634\u0648\u0631\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0628\u0627 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/peace-ipsc.org\/fa\/\u0635\u0646\u0639\u062a-\u0646\u0641\u062a-\u0648-\u06af\u0627\u0632-\u0627\u0645\u0627\u0631\u0627\u062a-\u0645\u062a\u062d\u062f\u0647-\u0639\u0631\u0628\u06cc\/\" \/>\n<meta property=\"og:site_name\" content=\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-27T00:08:11+00:00\" \/>\n<meta name=\"author\" content=\"ipsc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipsc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/\"},\"author\":{\"name\":\"ipsc\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe\"},\"headline\":\"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\",\"datePublished\":\"2022-08-27T00:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/\"},\"wordCount\":42,\"publisher\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\"},\"keywords\":[\"\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\",\"\u0627\u0646\u0631\u0698\u06cc\",\"\u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633\",\"\u06af\u0627\u0632\",\"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc\",\"\u0646\u0641\u062a\"],\"articleSection\":[\"\u0622\u0633\u06cc\u0627\",\"\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\",\"\u062e\u0627\u0648\u0631\u0645\u06cc\u0627\u0646\u0647\",\"\u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633\",\"\u06af\u0632\u06cc\u062f\u0647 \u0647\u0627\",\"\u0645\u0642\u0627\u0644\u0627\u062a\"],\"inLanguage\":\"fa-IR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/\",\"name\":\"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"isPartOf\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#website\"},\"datePublished\":\"2022-08-27T00:08:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/peace-ipsc.org\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#website\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/\",\"name\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/peace-ipsc.org\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\",\"name\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png\",\"contentUrl\":\"https:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png\",\"width\":269,\"height\":291,\"caption\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\"},\"image\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe\",\"name\":\"ipsc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g\",\"caption\":\"ipsc\"},\"url\":\"https:\/\/peace-ipsc.org\/fa\/author\/ipsc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/peace-ipsc.org\/fa\/\u0635\u0646\u0639\u062a-\u0646\u0641\u062a-\u0648-\u06af\u0627\u0632-\u0627\u0645\u0627\u0631\u0627\u062a-\u0645\u062a\u062d\u062f\u0647-\u0639\u0631\u0628\u06cc\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","og_description":"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d- IPSC \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc \u0634\u0627\u0645\u0644 \u0647\u0641\u062a \u0627\u0645\u0627\u0631\u062a &#8211; \u0627\u0628\u0648\u0638\u0628\u06cc\u060c \u0639\u062c\u0645\u0627\u0646\u060c \u062f\u0628\u06cc\u060c \u0641\u062c\u06cc\u0631\u0647\u060c \u0631\u0627\u0633 \u0627\u0644\u062e\u06cc\u0645\u0647\u060c \u0634\u0627\u0631\u062c\u0647 \u0648 \u0627\u0645 \u0627\u0644\u0642\u0648\u06cc\u0646 &#8211; \u0648\u0627\u0642\u0639 \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0633\u0627\u062d\u0644 \u062c\u0646\u0648\u0628 \u0634\u0631\u0642\u06cc \u0634\u0628\u0647 \u062c\u0632\u06cc\u0631\u0647 \u0639\u0631\u0628\u0633\u062a\u0627\u0646 \u0627\u0633\u062a. \u0627\u0632 \u0632\u0645\u0627\u0646 \u06a9\u0634\u0641 \u0646\u0641\u062a \u062f\u0631 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\u060c \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0628\u0647 \u06a9\u0634\u0648\u0631\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0628\u0627 [&hellip;]","og_url":"https:\/\/peace-ipsc.org\/fa\/\u0635\u0646\u0639\u062a-\u0646\u0641\u062a-\u0648-\u06af\u0627\u0632-\u0627\u0645\u0627\u0631\u0627\u062a-\u0645\u062a\u062d\u062f\u0647-\u0639\u0631\u0628\u06cc\/","og_site_name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","article_published_time":"2022-08-27T00:08:11+00:00","author":"ipsc","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"ipsc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"5 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#article","isPartOf":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/"},"author":{"name":"ipsc","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe"},"headline":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc","datePublished":"2022-08-27T00:08:11+00:00","mainEntityOfPage":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/"},"wordCount":42,"publisher":{"@id":"https:\/\/peace-ipsc.org\/fa\/#organization"},"keywords":["\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc","\u0627\u0646\u0631\u0698\u06cc","\u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633","\u06af\u0627\u0632","\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc","\u0646\u0641\u062a"],"articleSection":["\u0622\u0633\u06cc\u0627","\u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc","\u062e\u0627\u0648\u0631\u0645\u06cc\u0627\u0646\u0647","\u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633","\u06af\u0632\u06cc\u062f\u0647 \u0647\u0627","\u0645\u0642\u0627\u0644\u0627\u062a"],"inLanguage":"fa-IR"},{"@type":"WebPage","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/","url":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/","name":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","isPartOf":{"@id":"https:\/\/peace-ipsc.org\/fa\/#website"},"datePublished":"2022-08-27T00:08:11+00:00","breadcrumb":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%b5%d9%86%d8%b9%d8%aa-%d9%86%d9%81%d8%aa-%d9%88-%da%af%d8%a7%d8%b2-%d8%a7%d9%85%d8%a7%d8%b1%d8%a7%d8%aa-%d9%85%d8%aa%d8%ad%d8%af%d9%87-%d8%b9%d8%b1%d8%a8%db%8c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/peace-ipsc.org\/fa\/"},{"@type":"ListItem","position":2,"name":"\u0635\u0646\u0639\u062a \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc"}]},{"@type":"WebSite","@id":"https:\/\/peace-ipsc.org\/fa\/#website","url":"https:\/\/peace-ipsc.org\/fa\/","name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","description":"","publisher":{"@id":"https:\/\/peace-ipsc.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/peace-ipsc.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/peace-ipsc.org\/fa\/#organization","name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","url":"https:\/\/peace-ipsc.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png","contentUrl":"https:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png","width":269,"height":291,"caption":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d"},"image":{"@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe","name":"ipsc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g","caption":"ipsc"},"url":"https:\/\/peace-ipsc.org\/fa\/author\/ipsc\/"}]}},"_links":{"self":[{"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts\/14032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/comments?post=14032"}],"version-history":[{"count":0,"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts\/14032\/revisions"}],"wp:attachment":[{"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/media?parent=14032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/categories?post=14032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/tags?post=14032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}