{"id":13598,"date":"2022-01-18T05:19:33","date_gmt":"2022-01-18T05:19:33","guid":{"rendered":"https:\/\/peace-ipsc.org\/fa\/?p=13598"},"modified":"2022-01-18T05:19:33","modified_gmt":"2022-01-18T05:19:33","slug":"%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86","status":"publish","type":"post","link":"http:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/","title":{"rendered":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646"},"content":{"rendered":"<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><b>\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc<\/b><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><b>\u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9<\/b><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><b>\u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d<\/b><b>&#8211; IPSC<\/b><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u062f\u0631 \u06af\u0632\u0627\u0631\u0634 \u0633\u06cc\u0627\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0627\u06cc\u06cc\u0632 2012\u060c \u062f\u0628\u06cc\u0631\u06a9\u0644 \u0633\u0627\u0628\u0642 \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646\u060c \u0647\u0648 \u062c\u06cc\u0646\u062a\u0627\u0626\u0648\u060c \u0628\u0647 \u0647\u062c\u062f\u0647\u0645\u06cc\u0646 \u06a9\u0646\u06af\u0631\u0647 \u0645\u0644\u06cc \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u060c \u062a\u0627\u06a9\u06cc\u062f \u062f\u0627\u0634\u062a:\u00ab \u0645\u0627 \u0628\u0627\u06cc\u062f \u0638\u0631\u0641\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u0645\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u06cc\u0645\u060c \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0646\u06cc\u0645\u060c \u0642\u0627\u0637\u0639\u0627\u0646\u0647 \u0627\u0632 \u062d\u0642\u0648\u0642 \u0648 \u0645\u0646\u0627\u0641\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0646\u06cc\u0645 \u0648 \u0686\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0646\u06cc\u0645\u00bb. \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0622\u062e\u0631\u06cc\u0646 \u0628\u06cc\u0627\u0646\u06cc\u0647 \u00ab\u0647\u0648\u00bb \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0631\u0647\u0628\u0631 \u0627\u0631\u0634\u062f \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646 \u0628\u0648\u062f. \u0648\u06cc \u067e\u0633 \u0627\u0632 \u062a\u062d\u0648\u06cc\u0644 \u0622\u0646 \u0627\u0632 \u0633\u0650\u0645\u062a \u062e\u0648\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062f\u0628\u06cc\u0631\u06a9\u0644 \u0648 \u0631\u0626\u06cc\u0633 \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u0646\u0638\u0627\u0645\u06cc \u0645\u0631\u06a9\u0632\u06cc \u06a9\u0646\u0627\u0631\u0647 \u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f \u0648 \u0634\u06cc \u062c\u06cc\u0646 \u067e\u06cc\u0646\u06af \u0631\u0626\u06cc\u0633 \u062c\u0645\u0647\u0648\u0631 \u0641\u0639\u0644\u06cc \u062c\u0627\u0646\u0634\u06cc\u0646 \u0648\u06cc \u06af\u0631\u062f\u06cc\u062f. \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0627\u0646\u062a\u0642\u0627\u0644 \u0642\u062f\u0631\u062a \u0631\u0647\u0628\u0631\u06cc \u062f\u0631 \u062a\u0639\u0647\u062f \u0633\u0627\u062e\u062a \u0686\u06cc\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u06cc\u06a9 \u0647\u062f\u0641 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0645\u06cc\u0627\u0646 \u0645\u062f\u062a \u0648 \u0628\u0644\u0646\u062f \u0645\u062f\u062a \u062a\u0639\u06cc\u06cc\u0646 \u0634\u062f\u0647 \u0628\u0648\u062f\u060c \u062a\u063a\u06cc\u06cc\u0631\u06cc \u0628\u0647 \u0648\u062c\u0648\u062f \u0646\u06cc\u0627\u0648\u0631\u062f. \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0645\u0639\u062a\u0642\u062f\u0646\u062f \u0633\u0627\u062e\u062a \u0686\u06cc\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0631\u0627\u0647\u06cc \u0627\u0633\u0627\u0633\u06cc \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u067e\u0627\u06cc\u062f\u0627\u0631 \u0645\u0644\u062a \u0686\u06cc\u0646 \u0648 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062c\u0627\u06cc\u06af\u0627\u0647 \u062c\u0647\u0627\u0646\u06cc \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a\u060c \u0686\u0631\u0627\u06a9\u0647 \u06a9\u0634\u0648\u0631\u06cc \u0627\u0632 \u0645\u0632\u06cc\u062a \u0647\u0627\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0633\u0648\u062f \u0645\u06cc \u0628\u0631\u062f \u06a9\u0647 \u0627\u0632 \u0646\u0638\u0631 \u062a\u0648\u0633\u0639\u0647\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647\u060c \u062d\u0641\u0627\u0638\u062a\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0648 \u06a9\u0646\u062a\u0631\u0644 \u062f\u0631\u06cc\u0627\u0647\u0627 \u0627\u0632 \u0642\u062f\u0631\u062a \u0641\u0631\u0627\u0648\u0627\u0646\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<p dir=\"rtl\"><!--more--><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627\u060c \u0686\u06cc\u0646 \u0627\u0632 \u062a\u062c\u0631\u0628\u06cc\u0627\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0648\u062f \u0633\u0647 \u062f\u0631\u0633 \u0622\u0645\u0648\u062e\u062a\u0647 \u0627\u0633\u062a: 1)\u062f\u0627\u0634\u062a\u0646 \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0642\u0648\u06cc \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0633\u0631\u0632\u0645\u06cc\u0646 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a\u061b 2)\u0645\u0644\u062a\u06cc \u06a9\u0647 \u0627\u0647\u0645\u06cc\u062a \u062f\u0631\u06cc\u0627 \u0631\u0627 \u0646\u0641\u0647\u0645\u062f \u0622\u06cc\u0646\u062f\u0647 \u0627\u06cc \u0646\u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a\u061b 3)\u062f\u0648\u0644\u062a\u06cc \u06a9\u0647 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062f\u0641\u0627\u0639 \u0627\u0632 \u062d\u0642\u0648\u0642 \u0648 \u0645\u0631\u0632\u0647\u0627\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0646\u062f\u0627\u0631\u062f \u062f\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u062f\u062a \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0646\u062e\u0648\u0627\u0647\u062f \u0634\u062f. \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648 \u0637\u06cc \u0633\u0627\u0644\u06cc\u0627\u0646 \u06af\u0630\u0634\u062a\u0647 \u0686\u06cc\u0646 \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0631 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0648\u062f\u060c \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0645\u062a\u0639\u062f\u062f\u06cc \u0631\u0627 \u0645\u0627\u0646\u0646\u062f \u0633\u0627\u062e\u062a \u0627\u0648\u0644\u06cc\u0646 \u0646\u0627\u0648 \u0647\u0648\u0627\u067e\u06cc\u0645\u0627 \u0628\u0631\u060c \u0628\u0631\u06af\u0632\u0627\u0631\u06cc\u00a0 \u0631\u0632\u0645\u0627\u06cc\u0634 \u0647\u0627\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0628\u0627 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0645\u062a\u062d\u062f \u062e\u0648\u062f\u060c \u0634\u0631\u06a9\u062a \u062f\u0631 \u0631\u0632\u0645\u0627\u06cc\u0634 \u0647\u0627\u06cc \u0686\u0646\u062f \u062c\u0627\u0646\u0628\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0633\u0627\u062e\u062a \u0648 \u0633\u0627\u0632\u0647\u0627\u06cc \u0646\u0638\u0627\u0645\u06cc \u062f\u0631 \u062f\u0631\u06cc\u0627\u06cc \u0686\u06cc\u0646 \u062c\u0646\u0648\u0628\u06cc \u0648 \u0634\u0631\u0642\u06cc\u060c \u062d\u0636\u0648\u0631 \u062f\u0631 \u0628\u0646\u062f\u0631 \u06af\u0648\u0627\u062f\u0631 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u0648 \u0627\u0633\u062a\u0642\u0631\u0627\u0631 \u062f\u0648 \u0646\u0627\u0648\u0686\u0647 \u062c\u0646\u06af\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0628\u0646\u062f\u0631\u060c \u062a\u0627\u0633\u06cc\u0633 \u067e\u0627\u06cc\u06af\u0627\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u06a9\u0634\u0648\u0631 \u062c\u06cc\u0628\u0648\u062a\u06cc \u0648 \u062d\u0636\u0648\u0631 \u0641\u0639\u0627\u0644 \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0647\u0646\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f. \u062c\u0627\u0645\u0639\u0647 \u062c\u0647\u0627\u0646\u06cc \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0627\u062e\u06cc\u0631 \u0686\u06cc\u0646 \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u062f\u0631\u06cc\u0627\u0647\u0627 \u0631\u0627 \u0646\u0645\u0627\u06cc\u0627\u0646\u06af\u0631 \u062a\u0648\u0633\u0639\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0645\u06cc \u062f\u0627\u0646\u062f \u0648 \u0686\u06cc\u0646 \u0639\u0644\u0627\u0642\u0645\u0646\u062f \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0646 \u0628\u0647 \u06cc\u06a9 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0633\u062a. \u0628\u062f\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628\u060c \u0686\u06cc\u0646 \u062f\u0631 \u0633\u0646\u062f \u0633\u06cc\u0627\u0633\u062a \u0647\u0627\u06cc \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc(\u0628\u062e\u0634\u06cc \u0627\u0632 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc) \u062f\u0631 2012 \u0631\u0627\u0628\u0637\u0647 \u0628\u06cc\u0646 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0648 \u0633\u06cc\u0627\u0633\u062a \u0648 \u062d\u0648\u0632\u0647 \u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637\u0647 \u0631\u0627 \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc \u062f\u0647\u062f:<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><span style=\"font-weight: 400\">\u00ab\u0633\u06cc\u0627\u0633\u062a \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u06cc\u06a9 \u06a9\u062f \u0631\u0641\u062a\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u060c \u0628\u0631\u0646\u0627\u0645\u0647 \u0647\u0627\u06cc \u062a\u0648\u0633\u0639\u0647 \u0648 \u0631\u0648\u0627\u0628\u0637 \u062e\u0627\u0631\u062c\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u062f\u0631\u06cc\u0627\u0647\u0627\u061b \u0628\u0648\u062c\u0648\u062f \u0622\u0645\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u0631 \u0627\u06cc\u0646 \u0627\u0633\u0627\u0633 \u06cc\u06a9 \u0633\u06cc\u0627\u0633\u062a \u0645\u0647\u0645 \u0648 \u0628\u0646\u06cc\u0627\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0647\u062f\u0627\u0641 \u0648 \u0645\u0646\u0627\u0641\u0639 \u062f\u0648\u0644\u062a \u0631\u0627 \u062f\u0631 \u0628\u0631 \u0645\u06cc \u06af\u06cc\u0631\u062f. \u0627\u06cc\u0646 \u0633\u06cc\u0627\u0633\u062a \u0647\u0627 \u0634\u0627\u0645\u0644 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0631\u06cc\u0627\u0647\u0627 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0646\u0627\u0637\u0642 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062a\u0648\u0633\u0639\u0647 \u0648 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u062c\u0632\u0627\u06cc\u0631 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0639\u0644\u0645 \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0635\u0646\u0627\u06cc\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062a\u0628\u0644\u06cc\u063a\u0627\u062a &#8211; \u0622\u0645\u0648\u0632\u0634 \u0648 \u062a\u0648\u0633\u0639\u0647 \u0645\u0646\u0627\u0628\u0639 \u0627\u0646\u0633\u0627\u0646\u06cc \u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0635\u0646\u0627\u06cc\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0634\u0627\u0645\u0644 \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644\u060c \u062a\u0648\u0631\u06cc\u0633\u0645 &#8211; \u06af\u0631\u062f\u0634\u06af\u0631\u06cc\u060c \u0634\u06cc\u0644\u0627\u062a\u060c \u062a\u0648\u0633\u0639\u0647 \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0648 \u0633\u0627\u062e\u062a \u062a\u062c\u0647\u06cc\u0632\u0627\u062a \u0645\u0647\u0646\u062f\u0633\u06cc \u0627\u0633\u062a. \u0633\u0627\u0632\u0645\u0627\u0646(\u0627\u0631\u06af\u0627\u0646) \u062f\u0648\u0644\u062a\u06cc<\/span> <span style=\"font-weight: 400\">(SOA)<\/span> <span style=\"font-weight: 400\">\u0645\u0633\u0626\u0648\u0644 \u0627\u062c\u0631\u0627\u06cc \u0633\u06cc\u0627\u0633\u062a \u0647\u0627\u06cc \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u0627\u0633\u062a \u0627\u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0627\u062e\u062a\u06cc\u0627\u0631\u0627\u062a \u06a9\u0627\u0645\u0644 \u0646\u062f\u0627\u0631\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u062d\u062f\u0627\u0642\u0644 \u0628\u06cc\u0634 \u0627\u0632 30 \u0627\u0631\u06af\u0627\u0646 \u0645\u062e\u062a\u0644\u0641 \u062d\u0632\u0628\u06cc \u0648 \u062f\u0648\u0644\u062a\u06cc \u062f\u0631 \u062c\u0646\u0628\u0647 \u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0633\u06cc\u0627\u0633\u062a \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0647\u0627 \u0646\u0642\u0634 \u062f\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0631\u062f\u0647 \u0647\u0627\u06cc \u0627\u0633\u062a\u0627\u0646\u06cc\u060c \u062f\u0648\u0644\u062a \u0647\u0627\u06cc \u0645\u062d\u0644\u06cc \u062f\u0631 \u0627\u0645\u062a\u062f\u0627\u062f \u0633\u0627\u062d\u0644 \u0627\u0633\u062a\u0627\u0646 \u0647\u0627\u06cc \u0644\u06cc\u0627\u0626\u0648\u0646\u06cc\u0646\u06af\u060c \u0647\u0628\u06cc\u060c \u0634\u0627\u0646\u062f\u0648\u0646\u06af\u060c \u062c\u06cc\u0627\u0646\u06af \u0633\u0648\u060c \u0698\u062c\u06cc\u0627\u0646\u06af\u060c \u0641\u0648\u062c\u06cc\u0627\u0646\u060c \u06af\u0648\u0627\u0646\u06af\u062f\u0648\u0646\u06af \u0648 \u0647\u0627\u06cc\u0646\u0627\u0646\u061b \u0648 \u0634\u0647\u0631\u062f\u0627\u0631\u06cc \u0647\u0627\u06cc \u0627\u0633\u062a\u0627\u0646 \u062a\u06cc\u0627\u0646\u062c\u06cc\u0646 \u0648 \u0634\u0627\u0646\u06af\u0647\u0627\u06cc \u0648 \u0645\u0646\u0637\u0642\u0647 \u062e\u0648\u062f\u0645\u062e\u062a\u0627\u0631 \u06af\u0648\u0627\u0646\u06af\u0634\u06cc \u0648 \u062d\u0648\u0632\u0647 \u0647\u0627\u06cc \u0642\u0636\u0627\u06cc\u06cc \u062a\u062d\u062a \u0646\u0638\u0631 \u0622\u0646\u0647\u0627 \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0633\u06cc\u0627\u0633\u062a \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u0647\u0645\u0631\u0627\u0647 \u0647\u0633\u062a\u0646\u062f.<\/span><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0647\u0645\u0686\u0646\u06cc\u0646 \u06a9\u0646\u06af\u0631\u0647 \u0645\u0644\u06cc \u062e\u0644\u0642 \u062f\u0631 \u0645\u0627\u0631\u0633 2013 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0631\u0627 \u0627\u0632 \u0634\u0648\u0631\u0627\u06cc \u0627\u06cc\u0627\u0644\u062a\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u0646\u06af\u0631\u06cc \u062f\u0631 \u0627\u0631\u06af\u0627\u0646\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u06a9\u0647 \u0633\u06cc\u0627\u0633\u062a \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u06a9\u0646\u0646\u062f\u060c \u062a\u0635\u0648\u06cc\u0628 \u06a9\u0631\u062f \u06a9\u0647 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062f\u0648 \u0646\u06a9\u062a\u0647\u060c \u062a\u0646\u0638\u06cc\u0645\u0627\u062a \u062e\u0627\u0635\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f. \u0627\u0648\u0644\u060c \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062a\u0642\u0648\u06cc\u062a \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u062c\u0627\u0645\u0639 \u0645\u0633\u0627\u0626\u0644 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc\u060c \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u0645\u0644\u06cc \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0627\u0631\u06af\u0627\u0646 \u0646\u0638\u0627\u0631\u062a \u0633\u0637\u062d \u0628\u0627\u0644\u0627 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u062f. \u0627\u06cc\u0646 \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u062a\u062f\u0648\u06cc\u0646 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062a\u0648\u0633\u0639\u0647 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633\u06cc \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0645\u062f\u062a \u0648 \u0628\u0644\u0646\u062f \u0645\u062f\u062a \u0686\u06cc\u0646 \u0648 \u0631\u0633\u06cc\u062f\u06af\u06cc \u0628\u0647 \u0627\u0645\u0648\u0631 \u0645\u0647\u0645 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u062f\u0631\u06cc\u0627\u0647\u0627 \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u062a\u0648\u0633\u0637 \u0627\u0631\u06af\u0627\u0646 \u062f\u0648\u0644\u062a\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u062f\u0648\u0645\u060c \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u0627\u062c\u0631\u0627\u06cc \u0642\u0627\u0646\u0648\u0646 \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0686\u0647\u0627\u0631 \u0627\u0631\u06af\u0627\u0646 \u0645\u0648\u062c\u0648\u062f &#8211; \u0646\u0638\u0627\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 (\u062a\u062d\u062a \u0627\u0631\u06af\u0627\u0646 \u062f\u0648\u0644\u062a\u06cc\u060c \u06af\u0627\u0631\u062f \u0633\u0627\u062d\u0644\u06cc \u0686\u06cc\u0646 (\u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0646\u06cc\u062a \u0639\u0645\u0648\u0645\u06cc)\u060c \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u06cc \u0627\u062c\u0631\u0627\u06cc \u0642\u0627\u0646\u0648\u0646 \u0634\u06cc\u0644\u0627\u062a (\u0648\u0632\u0627\u0631\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc) \u0648 \u062f\u0641\u062a\u0631 \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0642\u0627\u0686\u0627\u0642 \u06a9\u0627\u0644\u0627 (\u0627\u062f\u0627\u0631\u0647 \u06a9\u0644 \u06af\u0645\u0631\u06a9) &#8211; \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u062a\u062d\u062a \u0645\u062f\u06cc\u0631\u06cc\u062a \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0627\u0631\u06af\u0627\u0646 \u062f\u0648\u0644\u062a\u06cc \u0627\u062f\u063a\u0627\u0645 \u0634\u0648\u062f\u060c \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u062d\u0642\u0648\u0642 \u0648 \u0645\u0646\u0627\u0641\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u0648 \u0627\u0646\u062c\u0627\u0645 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u0627\u062c\u0631\u0627\u06cc \u0642\u0648\u0627\u0646\u06cc\u0646 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062a\u062d\u062a \u0639\u0646\u0648\u0627\u0646 \u0627\u062f\u0627\u0631\u0647 \u067e\u0644\u06cc\u0633 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u062f(1).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0637\u0628\u0642 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0647\u0627\u06cc \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u06a9\u0647 \u0686\u06cc\u0646 \u062f\u0631 \u062d\u0648\u0632\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0628\u0627 \u0622\u0646 \u0631\u0648\u0628\u0631\u0648 \u0627\u0633\u062a \u0645\u0634\u0627\u0628\u0647 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u0647\u0627\u06cc \u0645\u0634\u062e\u0635 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u0622\u0644\u0641\u0631\u062f \u062a\u0627\u06cc\u0631\u0645\u0627\u0647\u0627\u0646 \u062f\u0631 \u0627\u062b\u0631 \u0645\u0639\u0631\u0648\u0641 \u062e\u0648\u062f \u06cc\u0639\u0646\u06cc \u00ab\u062a\u0623\u062b\u06cc\u0631 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627 \u0628\u0631 \u0627\u0646\u0642\u0644\u0627\u0628 \u0648 \u0627\u0645\u067e\u0631\u0627\u062a\u0648\u0631\u06cc \u0641\u0631\u0627\u0646\u0633\u0647\u060c \u0648 \u0639\u0644\u0627\u0642\u0647 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0647 \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627 \u060c \u062d\u0627\u0644 \u0648 \u0622\u06cc\u0646\u062f\u0647\u00bb\u060c \u0627\u0633\u062a. \u062a\u0635\u0648\u0631 \u0645\u06cc \u0634\u0648\u062f \u06a9\u0647 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0627\u0626\u06cc\u0628 \u0648 \u0646\u0638\u0631\u06cc\u0647 \u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633 \u0622\u0644\u0641\u0631\u062f \u0645\u0627\u0647\u0627\u0646 \u0645\u0634\u0627\u0628\u0647 \u0646\u06af\u0631\u0627\u0646\u06cc \u0686\u06cc\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u062f\u0631\u06cc\u0627\u06cc \u0686\u06cc\u0646 \u062c\u0646\u0648\u0628\u06cc\u060c \u062a\u0627\u06cc\u0648\u0627\u0646\u060c \u0634\u0628\u0647 \u062c\u0632\u06cc\u0631\u0647 \u06a9\u0631\u0647 \u0648 \u0698\u0627\u067e\u0646 \u0627\u0633\u062a. \u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u062a\u0627\u06cc\u0648\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0627\u0647\u0645\u06cc\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0686\u06cc\u0646 \u062f\u0627\u0631\u062f. \u0627\u06af\u0631 \u0686\u06cc\u0646 \u0628\u062e\u0648\u0627\u0647\u062f \u0642\u062f\u0631\u062a \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u062f\u0648\u0645\u06cc\u0646 \u0632\u0646\u062c\u06cc\u0631\u0647 \u062c\u0632\u06cc\u0631\u0647 \u067e\u06cc\u0634 \u0628\u06cc\u0646\u06cc \u06a9\u0646\u062f\u060c \u0627\u0648\u0644\u06cc\u0646 \u06af\u0627\u0645 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644 \u062a\u0627\u06cc\u0648\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u062a\u0627\u06cc\u0648\u0627\u0646 \u062f\u0631 \u0686\u0627\u0631\u0686\u0648\u0628 \u06cc\u06a9 \u062a\u0626\u0648\u0631\u06cc \u0645\u0627\u0647\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u0686\u06cc\u0646 \u06cc\u06a9 \u062f\u0627\u0631\u0627\u06cc\u06cc \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0622\u06cc\u062f(2).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0646\u0638\u0627\u0645\u06cc \u0645\u0639\u062a\u0642\u062f\u0646\u062f \u0686\u06cc\u0646 \u062f\u0631 \u0645\u0631\u062d\u0644\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0646 \u0628\u0647 \u06cc\u06a9 \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0622\u062a\u0644\u0627\u0646\u062a\u06cc\u06a9(\u0627\u0637\u0644\u0633) \u0627\u0633\u062a\u060c \u0686\u0631\u0627\u06a9\u0647 \u0627\u0632 \u0633\u0627\u06442014\u060c \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0627\u0637\u0644\u0633 \u062c\u0646\u0648\u0628\u06cc \u0627\u0632 \u0628\u0627\u0632\u062f\u06cc\u062f \u0646\u0645\u0627\u062f\u06cc\u0646 \u0648 \u0638\u0627\u0647\u0631\u06cc \u0628\u0646\u0627\u062f\u0631 \u0648 \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u0645\u0634\u062a\u0631\u06a9 \u0628\u0647 \u0639\u0645\u0644\u06cc\u0627\u062a \u0645\u0633\u062a\u0642\u0644 \u062f\u0631 \u062f\u0631\u06cc\u0627 \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u062f\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0647 \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0628\u0627 \u0645\u062d\u06cc\u0637 \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u0622\u0634\u0646\u0627 \u0634\u0648\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u0627\u0633\u062a \u06a9\u0647 \u0631\u0647\u0628\u0631\u0627\u0646 \u063a\u06cc\u0631\u0646\u0638\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0641\u0638\u062a \u0627\u0632 \u0645\u0646\u0627\u0641\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0631\u0648 \u0628\u0647 \u0631\u0634\u062f \u0686\u06cc\u0646 \u062f\u0631 \u0645\u0646\u0637\u0642\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u0645\u0648\u062b\u0631 \u067e\u0627\u0633\u062e \u062f\u0647\u0646\u062f. \u0636\u0645\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062d\u0636\u0648\u0631 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0627\u0637\u0644\u0633 \u062c\u0646\u0648\u0628\u06cc \u0646\u06cc\u0632 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0646\u0639\u06a9\u0633 \u06a9\u0646\u0646\u062f\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0631 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u067e\u06a9\u0646 \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u062a\u0647\u062f\u06cc\u062f\u0627\u062a \u0627\u0631\u062a\u0634 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0622\u0631\u0627\u0645 \u0628\u0627\u0634\u062f(3).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0686\u06cc\u0646 \u0647\u0645\u0686\u0646\u0627\u0646 \u062f\u0631\u06af\u06cc\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u0633\u0627\u062e\u062a \u06a9\u0634\u062a\u06cc \u0645\u062f\u0631\u0646 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0642\u0648\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0627\u0645\u0644 \u0632\u06cc\u0631\u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062c\u0646\u06af\u0646\u062f\u0647 \u0647\u0627\u06cc \u0633\u0637\u062d\u06cc\u060c \u06a9\u0634\u062a\u06cc \u062c\u0646\u06af\u06cc \u062f\u0648\u0632\u06cc\u0633\u062a\u060c \u0646\u0627\u0648\u0647\u0627\u06cc \u0647\u0648\u0627\u067e\u06cc\u0645\u0627\u0628\u0631 \u0648 \u06a9\u0634\u062a\u06cc \u0647\u0627\u06cc \u06a9\u0645\u06a9\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0627\u0631\u0633\u0627\u0644 \u0633\u0644\u0627\u062d \u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u060c \u0633\u0646\u0633\u0648\u0631\u0647\u0627 \u0648 \u0642\u0627\u0628\u0644\u06cc\u062a \u0647\u0627\u06cc \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644 \u0627\u0633\u062a. \u0686\u06cc\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u06cc\u062c\u0627\u062f \u062a\u062f\u0627\u0631\u06a9\u0627\u062a \u0642\u0648\u06cc \u0648 \u0632\u06cc\u0631\u0628\u0646\u0627\u06cc\u06cc \u067e\u0627\u06cc\u0647 \u062f\u0631 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0627\u0631\u062a\u0634 \u0622\u0632\u0627\u062f\u06cc \u0628\u062e\u0634 \u062e\u0644\u0642 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0642\u062f\u0631\u062a \u0646\u0638\u0627\u0645\u06cc \u0631\u0627 \u062f\u0631 \u0641\u0648\u0627\u0635\u0644 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0637\u0631\u0627\u062d\u06cc \u0648 \u062d\u0641\u0638 \u06a9\u0646\u062f. \u0686\u06cc\u0646 \u062f\u0631 \u062d\u0627\u0644 \u0628\u0631\u0631\u0633\u06cc \u0648 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u0636\u0627\u0641\u06cc \u0644\u062c\u0633\u062a\u06cc\u06a9 \u0646\u0638\u0627\u0645\u06cc \u062f\u0631 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0634\u0648\u0631 \u062d\u062a\u06cc \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u067e\u0627\u06cc\u06af\u0627\u0647 \u0641\u0639\u0644\u06cc \u062e\u0648\u062f \u062f\u0631 \u06a9\u0634\u0648\u0631 \u062c\u06cc\u0628\u0648\u062a\u06cc \u0627\u0633\u062a. \u0686\u06cc\u0646 \u0645\u06a9\u0627\u0646 \u0647\u0627\u06cc \u0628\u0631\u0627\u06cc \u062a\u0623\u0633\u06cc\u0633\u0627\u062a \u062a\u062f\u0627\u0631\u06a9\u0627\u062a\u06cc \u0646\u0638\u0627\u0645\u06cc \u0627\u0631\u062a\u0634 \u062e\u0644\u0642 \u062f\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0646\u0638\u06cc\u0631 \u0645\u06cc\u0627\u0646\u0645\u0627\u0631\u060c \u062a\u0627\u06cc\u0644\u0646\u062f\u060c \u0633\u0646\u06af\u0627\u067e\u0648\u0631\u060c \u0627\u0646\u062f\u0648\u0646\u0632\u06cc\u060c \u067e\u0627\u06a9\u0633\u062a\u0627\u0646\u060c \u0633\u0631\u06cc\u0644\u0627\u0646\u06a9\u0627\u060c \u0627\u0645\u0627\u0631\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0639\u0631\u0628\u06cc\u060c \u06a9\u0646\u06cc\u0627\u060c \u062c\u0632\u0627\u06cc\u0631\u0633\u06cc\u0634\u0644\u060c \u062a\u0627\u0646\u0632\u0627\u0646\u06cc\u0627\u060c \u0622\u0646\u06af\u0648\u0644\u0627\u060c \u06a9\u0627\u0645\u0628\u0648\u062c \u0648 \u062a\u0627\u062c\u06cc\u06a9\u0633\u062a\u0627\u0646\u060c \u0628\u0631\u0627\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0646\u06cc\u0631\u0648\u0647\u0627\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0647\u0648\u0627\u06cc\u06cc \u0648 \u0632\u0645\u06cc\u0646\u06cc \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a\u060c \u0627\u0644\u0628\u062a\u0647 \u06a9\u0627\u0645\u0628\u0648\u062c \u0627\u0646\u0639\u0642\u0627\u062f \u062a\u0648\u0627\u0641\u0642 \u0646\u0627\u0645\u0647 \u0628\u0627 \u0686\u06cc\u0646 \u0631\u0627 \u0627\u0646\u06a9\u0627\u0631 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u06cc \u0634\u06a9 \u0686\u0646\u06cc\u0646 \u062a\u062f\u0627\u0631\u06a9\u0627\u062a \u06af\u0633\u062a\u0631\u062f\u0647 \u0646\u0638\u0627\u0645\u06cc \u0627\u0631\u062a\u0634 \u062e\u0644\u0642 \u0686\u06cc\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0639\u0645\u0644\u06cc\u0627\u062a \u0627\u0631\u062a\u0634 \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u062f\u062e\u0627\u0644\u062a \u06a9\u0631\u062f\u0647 \u0648 \u0627\u0646\u0639\u0637\u0627\u0641 \u067e\u0630\u06cc\u0631\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0639\u0645\u0644\u06cc\u0627\u062a \u062a\u0647\u0627\u062c\u0645\u06cc \u0639\u0644\u06cc\u0647 \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647\u00a0 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u062f(4).\u00a0<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0686\u06cc\u0646\u060c \u062d\u0627\u06a9\u0645\u06cc\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0645\u0631\u0632\u0628\u0646\u062f\u06cc \u0686\u06cc\u0646 \u0628\u0627 \u0647\u0645\u0633\u0627\u06cc\u06af\u0627\u0646 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u0645\u0634\u062e\u0635 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u062c\u062f\u06cc \u062a\u0631\u06cc\u0646 \u0622\u0646 \u062a\u0627\u06a9\u06cc\u062f \u0645\u062c\u062f\u062f \u0628\u0631 \u062d\u0642 \u062d\u0627\u06a9\u0645\u06cc\u062a \u0628\u0631 \u062a\u0627\u06cc\u0648\u0627\u0646 \u0627\u0633\u062a. \u062a\u0627\u06cc\u0648\u0627\u0646 \u062c\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0631\u062a\u0634 \u0622\u0632\u0627\u062f\u06cc \u0628\u062e\u0634 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0645\u0631\u06cc\u06a9\u0627 \u0642\u0631\u0627\u0631 \u06af\u06cc\u0631\u062f. \u0648\u0642\u062a\u06cc \u0686\u06cc\u0646 \u0627\u0632 \u062c\u0646\u06af \u0648 \u067e\u06cc\u0631\u0648\u0632\u06cc \u062f\u0631 \u062c\u0646\u06af \u0635\u062d\u0628\u062a \u0645\u06cc \u06a9\u0646\u062f\u060c \u0645\u0633\u062a\u0642\u06cc\u0645\u0627 \u0628\u0647 \u0633\u0646\u0627\u0631\u06cc\u0648\u06cc \u062a\u0627\u06cc\u0648\u0627\u0646 \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc \u06a9\u0646\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062a\u0627\u06cc\u0648\u0627\u0646 \u062f\u0631 \u0645\u0646\u0627\u0641\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u0645\u0647\u0645 \u0627\u0633\u062a.\u00a0<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0647\u0645\u0686\u0646\u06cc\u0646 \u0686\u06cc\u0646 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0647\u0646\u062f \u0631\u0627 \u062a\u062d\u062a \u0646\u0641\u0648\u0630 \u062e\u0648\u062f \u062f\u0631\u0622\u0648\u0631\u062f\u0647 \u0627\u0633\u062a. \u0686\u06cc\u0646 \u0627\u0632 \u062f\u0648\u0627\u0632\u062f\u0647 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u06af\u0634\u062a \u0647\u0627\u06cc \u0636\u062f \u062f\u0632\u062f\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u062e\u0644\u06cc\u062c \u0639\u062f\u0646 \u0648 \u062f\u0631\u06cc\u0627\u06cc \u0639\u0631\u0628 \u0634\u0645\u0627\u0644\u06cc \u0645\u0633\u062a\u0642\u0631 \u06a9\u0646\u062f \u0648 \u0645\u0627\u0646\u0648\u0631\u0647\u0627\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u06a9\u0627\u0631\u06a9\u0631\u062f \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u0648\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f. \u0627\u06cc\u0646 \u0645\u0627\u0645\u0648\u0631\u06cc\u062a \u0647\u0627\u060c \u0646\u06cc\u0631\u0648\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062e\u0644\u0642 \u0686\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0646\u06cc\u0631\u0648\u06cc \u062c\u0647\u0627\u0646\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0645\u0644\u0632\u0645 \u0628\u0647 \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0645\u0633\u0627\u0626\u0644 \u0644\u062c\u0633\u062a\u06cc\u06a9\u060c \u0641\u0631\u0645\u0627\u0646\u062f\u0647\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644\u060c \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0648 \u062a\u0639\u0645\u06cc\u0631 \u0627\u0632 \u0646\u0627\u0648\u06af\u0627\u0646 \u062e\u0648\u062f \u0645\u06cc \u06a9\u0646\u062f\u060c \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631 \u062a\u062c\u0631\u0628\u0647 \u0628\u0647 \u062f\u0633\u062a \u0622\u0645\u062f\u0647 \u062a\u0648\u0633\u0637 \u0627\u0641\u0633\u0631\u0627\u0646 \u0648 \u062e\u062f\u0645\u0647 \u0645\u0633\u062a\u0642\u0631 \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0648 \u06a9\u0627\u0631\u0622\u0645\u062f \u0628\u0648\u062f\u0647 \u0627\u0633\u062a\u060c \u0686\u0631\u0627\u06a9\u0647 \u06af\u0634\u062a \u0647\u0627\u06cc \u0636\u062f \u062f\u0632\u062f\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u0638\u0631\u0641\u06cc\u062a \u0647\u0627\u06cc \u0627\u0645\u0646\u06cc\u062a\u06cc \u0686\u06cc\u0646 \u0628\u062e\u0635\u0648\u0635 \u062f\u0631 \u0645\u0648\u0627\u062c\u0647\u0647 \u0628\u0627 \u0645\u0639\u0636\u0644 \u0645\u0627\u0644\u0627\u06a9\u0627 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0648\u0627\u0642\u0639\u06cc\u062a \u06a9\u0647 \u0647\u0646\u062f \u0627\u0632 \u0645\u0632\u06cc\u062a \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u062f\u0631 \u062a\u0646\u06af\u0647 \u0645\u0627\u0644\u0627\u06a9\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0686\u06cc\u0646 \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a\u060c \u067e\u06a9\u0646 \u0631\u0627 \u0645\u062c\u0628\u0648\u0631 \u06a9\u0631\u062f\u0647 \u062a\u0627 \u06af\u0632\u06cc\u0646\u0647 \u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0628\u0631\u0627\u06cc \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646\u06cc \u0645\u0648\u0631\u062f \u0628\u0631\u0631\u0633\u06cc \u0642\u0631\u0627\u0631 \u062f\u0647\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u062d\u0636\u0648\u0631 \u06a9\u0634\u062a\u06cc \u0647\u0627\u06cc \u062c\u0646\u06af\u06cc \u0686\u06cc\u0646 \u062f\u0631 \u0627\u0642\u06cc\u0627\u0646\u0648\u0633 \u0647\u0646\u062f\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u062f\u0631 \u062f\u0631\u06cc\u0627\u06cc \u0639\u0631\u0628\u060c \u0627\u0645\u0631\u06cc \u0639\u0627\u062f\u06cc \u062a\u0644\u0642\u06cc \u0645\u06cc \u0634\u0648\u062f \u0648 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627\u064b \u0628\u0647 \u0627\u0628\u062a\u06a9\u0627\u0631 \u0631\u0626\u06cc\u0633 \u062c\u0645\u0647\u0648\u0631 \u0634\u06cc \u062c\u06cc\u0646 \u067e\u06cc\u0646\u06af \u062f\u0631 \u0645\u0648\u0631\u062f \u062c\u0627\u062f\u0647 \u0627\u0628\u0631\u06cc\u0634\u0645 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0645\u0631\u062a\u0628\u0637 \u0627\u0633\u062a(5).<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">\u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u062a\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f \u0633\u06cc\u0627\u0633\u062a \u062e\u0627\u0631\u062c\u06cc \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u06af\u0633\u062a\u0631\u0634 \u0631\u0648\u0627\u0628\u0637 \u062f\u0648 \u062c\u0627\u0646\u0628\u0647 \u0648 \u062f\u0631 \u062d\u0627\u0644 \u062a\u0648\u0633\u0639\u0647 \u0628\u0627\u0634\u062f \u0686\u0631\u0627\u06a9\u0647 \u062d\u062c\u0645 \u0628\u0632\u0631\u06af \u062a\u062c\u0627\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0648 \u0645\u0631\u0627\u0648\u062f\u0627\u062a \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647 \u062a\u0648\u0627\u0632\u0646 \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u0628\u06cc\u0646 \u0642\u062f\u0631\u062a\u0647\u0627\u06cc \u062f\u0631\u06cc\u0627\u0645\u062d\u0648\u0631 \u06a9\u0647 \u062c\u0632\u0648 \u0642\u062f\u0631\u062a\u0647\u0627\u06cc \u0635\u0646\u0639\u062a\u06cc \u062f\u0631 \u0642\u0631\u0646 \u0628\u06cc\u0633\u062a \u0648 \u06cc\u06a9 \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0647 \u0648\u062c\u0648\u062f \u0645\u06cc \u0622\u0648\u0631\u062f \u0648 \u0648\u0632\u0646\u0647 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u0631\u0627 \u0628\u0647 \u0633\u0645\u062a \u0647\u0645\u06af\u0631\u0627\u06cc\u06cc \u0645\u062a\u0645\u0627\u06cc\u0644 \u0645\u06cc \u06a9\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-size: 12pt\"><b>\u06a9\u0644\u06cc\u062f \u0648\u0627\u0698\u06af\u0627\u0646: \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc, \u0686\u06cc\u0646, \u0627\u0645\u0631\u06cc\u06a9\u0627, \u0642\u062f\u0631\u062a \u0646\u0638\u0627\u0645\u06cc, \u062a\u0627\u06cc\u0648\u0627\u0646, \u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc<\/b><\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">1- Takeda Jun\u2019ichi, China&#8217;s Rise as a Maritime Power ,2014,<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">2-James R. Holmes and Toshi Yoshihara,Chinese Naval Strategy in the Twenty First Century:<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">3- Ryan D.Martinson, China as an Atlantic Naval Power,2019,pp:18-31,<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">4- China\u2019s Military Strategy,2015, https:\/\/news.usni.org\/2015\/05\/26\/<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\"><span style=\"font-weight: 400;font-size: 12pt\">5- Michael Mcdevitt, China as a Twenty First Century Naval Power,2021,<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d&#8211; IPSC \u062f\u0631 \u06af\u0632\u0627\u0631\u0634 \u0633\u06cc\u0627\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0627\u06cc\u06cc\u0632 2012\u060c \u062f\u0628\u06cc\u0631\u06a9\u0644 \u0633\u0627\u0628\u0642 \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646\u060c \u0647\u0648 \u062c\u06cc\u0646\u062a\u0627\u0626\u0648\u060c \u0628\u0647 \u0647\u062c\u062f\u0647\u0645\u06cc\u0646 \u06a9\u0646\u06af\u0631\u0647 \u0645\u0644\u06cc \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u060c \u062a\u0627\u06a9\u06cc\u062f \u062f\u0627\u0634\u062a:\u00ab \u0645\u0627 \u0628\u0627\u06cc\u062f \u0638\u0631\u0641\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u0645\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u06cc\u0645\u060c [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,1271,1232,11,3],"tags":[2573,4342,352,82,3290,3072],"class_list":["post-13598","post","type-post","status-publish","format-standard","hentry","category-21","category---articles","category-1232","category-11","category-articles","tag-2573","tag-4342","tag-352","tag-82","tag-3290","tag-3072"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/peace-ipsc.org\/fa\/\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc-\u0642\u062f\u0631\u062a-\u062f\u0631\u06cc\u0627\u06cc\u06cc-\u0686\u06cc\u0646\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d&#8211; IPSC \u062f\u0631 \u06af\u0632\u0627\u0631\u0634 \u0633\u06cc\u0627\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0627\u06cc\u06cc\u0632 2012\u060c \u062f\u0628\u06cc\u0631\u06a9\u0644 \u0633\u0627\u0628\u0642 \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646\u060c \u0647\u0648 \u062c\u06cc\u0646\u062a\u0627\u0626\u0648\u060c \u0628\u0647 \u0647\u062c\u062f\u0647\u0645\u06cc\u0646 \u06a9\u0646\u06af\u0631\u0647 \u0645\u0644\u06cc \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u060c \u062a\u0627\u06a9\u06cc\u062f \u062f\u0627\u0634\u062a:\u00ab \u0645\u0627 \u0628\u0627\u06cc\u062f \u0638\u0631\u0641\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u0645\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u06cc\u0645\u060c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/peace-ipsc.org\/fa\/\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc-\u0642\u062f\u0631\u062a-\u062f\u0631\u06cc\u0627\u06cc\u06cc-\u0686\u06cc\u0646\/\" \/>\n<meta property=\"og:site_name\" content=\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T05:19:33+00:00\" \/>\n<meta name=\"author\" content=\"ipsc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipsc\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/\"},\"author\":{\"name\":\"ipsc\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe\"},\"headline\":\"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646\",\"datePublished\":\"2022-01-18T05:19:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/\"},\"wordCount\":64,\"publisher\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\"},\"keywords\":[\"\u200e\u064f\u0652\u200e\u200f\u064c\u064f\u064b\",\"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc\",\"\u0627\u0645\u0631\u06cc\u06a9\u0627\",\"\u0686\u06cc\u0646\",\"\u0642\u062f\u0631\u062a \u0646\u0638\u0627\u0645\u06cc\",\"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc\"],\"articleSection\":[\"\u0622\u0633\u06cc\u0627\",\"\u0622\u0633\u06cc\u0627\u06cc \u0634\u0631\u0642\u06cc\",\"\u0686\u06cc\u0646\",\"\u06af\u0632\u06cc\u062f\u0647 \u0647\u0627\",\"\u0645\u0642\u0627\u0644\u0627\u062a\"],\"inLanguage\":\"fa-IR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/\",\"name\":\"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"isPartOf\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#website\"},\"datePublished\":\"2022-01-18T05:19:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/peace-ipsc.org\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#website\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/\",\"name\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/peace-ipsc.org\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#organization\",\"name\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\",\"url\":\"https:\/\/peace-ipsc.org\/fa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png\",\"contentUrl\":\"http:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png\",\"width\":269,\"height\":291,\"caption\":\"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d\"},\"image\":{\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe\",\"name\":\"ipsc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g\",\"caption\":\"ipsc\"},\"url\":\"http:\/\/peace-ipsc.org\/fa\/author\/ipsc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/peace-ipsc.org\/fa\/\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc-\u0642\u062f\u0631\u062a-\u062f\u0631\u06cc\u0627\u06cc\u06cc-\u0686\u06cc\u0646\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","og_description":"\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u0645\u0633\u0627\u0626\u0644 \u0698\u0626\u0648\u067e\u0644\u06cc\u062a\u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d&#8211; IPSC \u062f\u0631 \u06af\u0632\u0627\u0631\u0634 \u0633\u06cc\u0627\u0633\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0627\u06cc\u06cc\u0632 2012\u060c \u062f\u0628\u06cc\u0631\u06a9\u0644 \u0633\u0627\u0628\u0642 \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646\u060c \u0647\u0648 \u062c\u06cc\u0646\u062a\u0627\u0626\u0648\u060c \u0628\u0647 \u0647\u062c\u062f\u0647\u0645\u06cc\u0646 \u06a9\u0646\u06af\u0631\u0647 \u0645\u0644\u06cc \u062d\u0632\u0628 \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a \u0686\u06cc\u0646 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f\u060c \u062a\u0627\u06a9\u06cc\u062f \u062f\u0627\u0634\u062a:\u00ab \u0645\u0627 \u0628\u0627\u06cc\u062f \u0638\u0631\u0641\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u0645\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0647\u06cc\u0645\u060c [&hellip;]","og_url":"https:\/\/peace-ipsc.org\/fa\/\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc-\u0642\u062f\u0631\u062a-\u062f\u0631\u06cc\u0627\u06cc\u06cc-\u0686\u06cc\u0646\/","og_site_name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","article_published_time":"2022-01-18T05:19:33+00:00","author":"ipsc","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a":"ipsc","\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646":"7 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#article","isPartOf":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/"},"author":{"name":"ipsc","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe"},"headline":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646","datePublished":"2022-01-18T05:19:33+00:00","mainEntityOfPage":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/"},"wordCount":64,"publisher":{"@id":"https:\/\/peace-ipsc.org\/fa\/#organization"},"keywords":["\u200e\u064f\u0652\u200e\u200f\u064c\u064f\u064b","\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u062f\u0631\u06cc\u0627\u06cc\u06cc","\u0627\u0645\u0631\u06cc\u06a9\u0627","\u0686\u06cc\u0646","\u0642\u062f\u0631\u062a \u0646\u0638\u0627\u0645\u06cc","\u0645\u0631\u06cc\u0645 \u0648\u0631\u06cc\u062c \u06a9\u0627\u0638\u0645\u06cc"],"articleSection":["\u0622\u0633\u06cc\u0627","\u0622\u0633\u06cc\u0627\u06cc \u0634\u0631\u0642\u06cc","\u0686\u06cc\u0646","\u06af\u0632\u06cc\u062f\u0647 \u0647\u0627","\u0645\u0642\u0627\u0644\u0627\u062a"],"inLanguage":"fa-IR"},{"@type":"WebPage","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/","url":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/","name":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646 - IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","isPartOf":{"@id":"https:\/\/peace-ipsc.org\/fa\/#website"},"datePublished":"2022-01-18T05:19:33+00:00","breadcrumb":{"@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#breadcrumb"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/peace-ipsc.org\/fa\/%d8%a7%d8%b3%d8%aa%d8%b1%d8%a7%d8%aa%da%98%db%8c-%d9%82%d8%af%d8%b1%d8%aa-%d8%af%d8%b1%db%8c%d8%a7%db%8c%db%8c-%da%86%db%8c%d9%86\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/peace-ipsc.org\/fa\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc \u0642\u062f\u0631\u062a \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0686\u06cc\u0646"}]},{"@type":"WebSite","@id":"https:\/\/peace-ipsc.org\/fa\/#website","url":"https:\/\/peace-ipsc.org\/fa\/","name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","description":"","publisher":{"@id":"https:\/\/peace-ipsc.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/peace-ipsc.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/peace-ipsc.org\/fa\/#organization","name":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d","url":"https:\/\/peace-ipsc.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/","url":"http:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png","contentUrl":"http:\/\/peace-ipsc.org\/fa\/wp-content\/uploads\/sites\/2\/2023\/10\/IPSC-Logo.png","width":269,"height":291,"caption":"IPSC - \u0645\u0631\u06a9\u0632 \u0628\u06cc\u0646 \u0627\u0644\u0645\u0644\u0644\u06cc \u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0635\u0644\u062d"},"image":{"@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/5b4718a8e109f37c2a97015090236cbe","name":"ipsc","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/peace-ipsc.org\/fa\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8018a9e1dd012832c69248ba92bd6c4eaf994d760b0b81010e17759563ffefd?s=96&d=mm&r=g","caption":"ipsc"},"url":"http:\/\/peace-ipsc.org\/fa\/author\/ipsc\/"}]}},"_links":{"self":[{"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts\/13598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/comments?post=13598"}],"version-history":[{"count":0,"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/posts\/13598\/revisions"}],"wp:attachment":[{"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/media?parent=13598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/categories?post=13598"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/peace-ipsc.org\/fa\/wp-json\/wp\/v2\/tags?post=13598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}